{"id":7788,"count":1,"description":"","link":"https:\/\/devlipinews.com\/dn\/tag\/baloch-rebel\/","name":"Baloch Rebel","slug":"baloch-rebel","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/devlipinews.com\/dn\/wp-json\/wp\/v2\/tags\/7788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devlipinews.com\/dn\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/devlipinews.com\/dn\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/devlipinews.com\/dn\/wp-json\/wp\/v2\/posts?tags=7788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}